{"id":2388,"date":"2019-01-25T13:50:43","date_gmt":"2019-01-25T18:50:43","guid":{"rendered":"https:\/\/www.hedgeanswers.com\/?p=2388"},"modified":"2023-10-12T14:33:22","modified_gmt":"2023-10-12T14:33:22","slug":"nothing-new-here","status":"publish","type":"post","link":"https:\/\/aandcadvisors.com\/es\/nothing-new-here\/","title":{"rendered":"Nada nuevo"},"content":{"rendered":"<p>He pasado la mayor parte de esta semana recorriendo la ciudad de Nueva York para reunirme con amigos y enemigos de la comunidad de servicios financieros. Hubo una serie de actos en los que se presentaron varias empresas y sus servicios y se ofreci\u00f3 una \"visi\u00f3n \u00fanica\" de la situaci\u00f3n del sector de la gesti\u00f3n de inversiones. Los ponentes de los actos destacaron las tendencias tanto del lado del inversor como del gestor en la ecuaci\u00f3n de la gesti\u00f3n de fondos. He aqu\u00ed algunos de los temas y tendencias que debatieron estos finos observadores del sector de la gesti\u00f3n monetaria:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Descienden los lanzamientos de nuevos fondos<\/li>\n\n\n\n<li>Los inversores buscan gestores capaces de generar alfa<\/li>\n\n\n\n<li>Las criptomonedas y la cadena de bloques son reales y est\u00e1n aqu\u00ed para quedarse<\/li>\n\n\n\n<li>Los fondos de zonas de oportunidad est\u00e1n de moda<\/li>\n\n\n\n<li>El cannabis es algo que no se puede pasar por alto<\/li>\n\n\n\n<li>Los gestores colaboran estrechamente con los inversores en la estructuraci\u00f3n de los productos<\/li>\n\n\n\n<li>Hay demasiados proveedores de servicios en el sector<\/li>\n<\/ol>\n\n\n\n<p>No hay muchas novedades. La mayor\u00eda de estos temas y tendencias son los mismos de los que se viene hablando desde hace un par de a\u00f1os. Lo m\u00e1s importante para m\u00ed esta semana es que hay mucha gente que presta servicios al sector.  Aunque estoy a favor de la competencia y el libre mercado, parece que hay mucha gente vendiendo sus productos. Los precios est\u00e1n bajando y la gente est\u00e1 nerviosa por cumplir sus cuotas y captar nuevos clientes. He hablado con un pu\u00f1ado de inversores y directivos que me han comentado lo mismo: est\u00e1n inundados de solicitudes de reuniones de abogados, contables, directores, administradores, prime brokers, banqueros y empresas tecnol\u00f3gicas que quieren venderles algo que es m\u00e1s barato, mejor y m\u00e1s r\u00e1pido que lo que utilizan ahora. Esto no incluye a las empresas de recursos humanos, compa\u00f1\u00edas de seguros, grupos de n\u00f3minas y, por supuesto, cazatalentos. Parece un poco peligroso. Puede que haya demasiados cocineros en la cocina.<\/p>\n\n\n\n<p>Una noticia de la<a href=\"http:\/\/www.imdda.org\"> IMDDA<\/a>. Todav\u00eda hay tiempo para inscribirse en el examen CDDA. La ventana se ha ampliado hasta el 31 de marzo de 2019. Para obtener m\u00e1s informaci\u00f3n sobre lo que el <a href=\"http:\/\/www,imdda.org\">IMDDA<\/a> y para inscribirse en el examen, haga clic en <a href=\"http:\/\/www.imdda.org\">aqu\u00ed<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong data-rich-text-format-boundary=\"true\">Cosas que me vuelven loco<\/strong><\/h2>\n\n\n\n<p>La gente es simplemente maleducada. Vale, no todas las personas, s\u00f3lo las que creen que est\u00e1 bien utilizar un altavoz en un espacio p\u00fablico. Estas personas son simplemente odiosas y, francamente, su falta de respeto por el mundo en general se manifiesta cuando realizan este acto realmente espantoso. Recientemente, lo experiment\u00e9 mientras estaba en la pista esperando para despegar.  La llamada entre una madre y su hija versaba sobre los deberes de la ni\u00f1a, sus planes extraescolares y su reciente nota en un examen de matem\u00e1ticas. Yo y la mayor\u00eda de mis compa\u00f1eros sentados cerca sab\u00edamos todo esto porque la madre consider\u00f3 necesario utilizar el altavoz lo suficientemente alto como para que todos pudi\u00e9ramos o\u00edrla. Vamos, somos mejores que esto, \u00bfno?<\/p>","protected":false},"excerpt":{"rendered":"<p>I spent the better part of this week running around New York City meeting with friends and foes in the financial services community. There were a series of events that showcased a number of firms and their services as well as provided &#8220;unique insight&#8221; into the status of the investment management industry. Speakers at the [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2390,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[24],"tags":[],"class_list":["post-2388","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/aandcadvisors.com\/es\/wp-json\/wp\/v2\/posts\/2388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aandcadvisors.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aandcadvisors.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aandcadvisors.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/aandcadvisors.com\/es\/wp-json\/wp\/v2\/comments?post=2388"}],"version-history":[{"count":1,"href":"https:\/\/aandcadvisors.com\/es\/wp-json\/wp\/v2\/posts\/2388\/revisions"}],"predecessor-version":[{"id":4157,"href":"https:\/\/aandcadvisors.com\/es\/wp-json\/wp\/v2\/posts\/2388\/revisions\/4157"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aandcadvisors.com\/es\/wp-json\/wp\/v2\/media\/2390"}],"wp:attachment":[{"href":"https:\/\/aandcadvisors.com\/es\/wp-json\/wp\/v2\/media?parent=2388"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aandcadvisors.com\/es\/wp-json\/wp\/v2\/categories?post=2388"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aandcadvisors.com\/es\/wp-json\/wp\/v2\/tags?post=2388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}